{"id":35623,"date":"2025-09-10T14:35:11","date_gmt":"2025-09-10T17:35:11","guid":{"rendered":"https:\/\/metahospitalar.com.br\/sobre-nosotros\/"},"modified":"2026-05-12T11:41:50","modified_gmt":"2026-05-12T14:41:50","slug":"sobre-nosotros","status":"publish","type":"page","link":"https:\/\/metahospitalar.com.br\/es\/sobre-nosotros\/","title":{"rendered":"Sobre nosotros"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"35623\" class=\"elementor elementor-35623 elementor-1045\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-db37672 e-flex e-con-boxed e-con e-parent\" data-id=\"db37672\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-33a0e1f e-con-full e-flex e-con e-child\" data-id=\"33a0e1f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-d2ba262 e-con-full e-flex e-con e-child\" data-id=\"d2ba262\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-606b77e elementor-widget elementor-widget-heading\" data-id=\"606b77e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Conozca de cerca Metahospitalar.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-aadb365 e-con-full e-flex e-con e-child\" data-id=\"aadb365\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-efeda39 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"efeda39\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Lo invitamos a conocer nuestra estructura industrial, nuestros productos y las soluciones que desarrollamos para hospitales e instituciones de salud.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-65f47e3 ct-button-icon elementor-widget elementor-widget-button\" data-id=\"65f47e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#conhe\u00e7a\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Layer_1\" viewBox=\"0 0 40 40\"><path d=\"M20,0C9,0,0,9,0,20s9,20,20,20,20-9,20-20S31,0,20,0ZM28.6,20h0c0,.1,0,.2,0,.3,0,0,0,0,0,0h0c0,0,0,.1-.1.2h0s-6.9,7-6.9,7c-.2.3-.7.3-.9,0,0,0,0,0,0,0-.3-.3-.3-.7,0-.9,0,0,0,0,0,0l5.8-5.9h-14.5c-.4,0-.6-.3-.6-.7,0-.4.3-.6.6-.6h14.5l-5.8-5.9c-.2-.3-.2-.7,0-.9.3-.2.7-.2.9,0l6.9,7h0c0,0,0,.1.1.2h0s0,0,0,0h0c0,0,0,.2,0,.2h0s0,0,0,0Z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Conocer<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e6e8a7a e-flex e-con-boxed e-con e-parent\" data-id=\"e6e8a7a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7940d9b elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"7940d9b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nuestra Pol\u00edtica de Calidad<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0281094 e-flex e-con-boxed e-con e-parent\" data-id=\"0281094\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-80076e6 elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"80076e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"168\" height=\"196\" src=\"https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2024\/02\/politica-de-qualidade.png\" class=\"attachment-medium size-medium wp-image-22693\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h5 class=\"elementor-image-box-title\">Pol\u00edtica de calidad<\/h5><p class=\"elementor-image-box-description\">Atender, superar y sorprender las expectativas del mercado mediante una excelente atenci\u00f3n, proporcionando mobiliario hospitalario de desempe\u00f1o superior. Valorar la capacitaci\u00f3n y el compromiso del equipo. <\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-afd49fd elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"afd49fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img fetchpriority=\"high\" decoding=\"async\" width=\"500\" height=\"316\" src=\"https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2026\/03\/bbf-e1774379851710-500x316.png\" class=\"attachment-medium size-medium wp-image-35618\" alt=\"\" srcset=\"https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2026\/03\/bbf-e1774379851710-500x316.png 500w, https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2026\/03\/bbf-e1774379851710-300x190.png 300w, https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2026\/03\/bbf-e1774379851710-768x485.png 768w, https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2026\/03\/bbf-e1774379851710-600x379.png 600w, https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2026\/03\/bbf-e1774379851710.png 1060w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure><div class=\"elementor-image-box-content\"><h5 class=\"elementor-image-box-title\">Boas Pr\u00e1ticas de Fabrica\u00e7\u00e3o<\/h5><p class=\"elementor-image-box-description\">Mantener la mejora continua del proceso productivo mediante normas y herramientas de calidad, con el fin de garantizar la excelencia de los productos.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c457ed2 e-flex e-con-boxed e-con e-parent\" data-id=\"c457ed2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-39aaa69 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"39aaa69\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Vea nuestros certificados.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0f4eb26 e-grid e-con-boxed e-con e-parent\" data-id=\"0f4eb26\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-874d825 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"874d825\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"873\" height=\"873\" src=\"https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2024\/11\/iso-13485.webp\" class=\"attachment-full size-full wp-image-25084\" alt=\"\" srcset=\"https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2024\/11\/iso-13485.webp 873w, https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2024\/11\/iso-13485-300x300.webp 300w, https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2024\/11\/iso-13485-100x100.webp 100w, https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2024\/11\/iso-13485-600x600.webp 600w, https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2024\/11\/iso-13485-150x150.webp 150w, https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2024\/11\/iso-13485-768x768.webp 768w, https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2024\/11\/iso-13485-50x50.webp 50w\" sizes=\"(max-width: 873px) 100vw, 873px\" \/><\/figure><div class=\"elementor-image-box-content\"><h5 class=\"elementor-image-box-title\">ISO 13485<\/h5><p class=\"elementor-image-box-description\">Certificaci\u00f3n internacional del sistema de gesti\u00f3n de calidad, espec\u00edfica para empresas que dise\u00f1an dispositivos m\u00e9dicos.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f25f9b6 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"f25f9b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"872\" height=\"873\" src=\"https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2024\/11\/iso-9001.webp\" class=\"attachment-full size-full wp-image-25087\" alt=\"\" srcset=\"https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2024\/11\/iso-9001.webp 872w, https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2024\/11\/iso-9001-300x300.webp 300w, https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2024\/11\/iso-9001-100x100.webp 100w, https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2024\/11\/iso-9001-600x601.webp 600w, https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2024\/11\/iso-9001-150x150.webp 150w, https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2024\/11\/iso-9001-768x769.webp 768w, https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2024\/11\/iso-9001-50x50.webp 50w\" sizes=\"(max-width: 872px) 100vw, 872px\" \/><\/figure><div class=\"elementor-image-box-content\"><h5 class=\"elementor-image-box-title\">ISO 9001<\/h5><p class=\"elementor-image-box-description\">Reconocimiento internacional de un sistema de gesti\u00f3n de calidad eficiente, enfocado en la mejora continua y en la satisfacci\u00f3n del cliente.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-39ad5c4 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"39ad5c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"872\" height=\"873\" src=\"https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2024\/11\/FDA.webp\" class=\"attachment-2048x2048 size-2048x2048 wp-image-25090\" alt=\"\" srcset=\"https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2024\/11\/FDA.webp 872w, https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2024\/11\/FDA-300x300.webp 300w, https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2024\/11\/FDA-100x100.webp 100w, https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2024\/11\/FDA-600x601.webp 600w, https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2024\/11\/FDA-150x150.webp 150w, https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2024\/11\/FDA-768x769.webp 768w, https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2024\/11\/FDA-50x50.webp 50w\" sizes=\"(max-width: 872px) 100vw, 872px\" \/><\/figure><div class=\"elementor-image-box-content\"><h5 class=\"elementor-image-box-title\">Food and Drug Administration<\/h5><p class=\"elementor-image-box-description\">Las camas electrom\u00e9dicas cumplen con las rigurosas normas de seguridad, calidad y eficacia exigidas por la agencia reguladora de los Estados Unidos.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1036e8b elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"1036e8b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"301\" height=\"301\" src=\"https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2026\/03\/anvisa-1.png\" class=\"attachment-full size-full wp-image-35619\" alt=\"\" srcset=\"https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2026\/03\/anvisa-1.png 301w, https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2026\/03\/anvisa-1-100x100.png 100w, https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2026\/03\/anvisa-1-50x50.png 50w\" sizes=\"(max-width: 301px) 100vw, 301px\" \/><\/figure><div class=\"elementor-image-box-content\"><h5 class=\"elementor-image-box-title\">ANVISA<\/h5><p class=\"elementor-image-box-description\">Productos probados, aprobados y que cumplen con las normas de seguridad, calidad y eficacia de la Agencia Nacional de Vigilancia Sanitaria.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8df3a0f elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"8df3a0f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"873\" height=\"873\" src=\"https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2024\/11\/qccert.webp\" class=\"attachment-full size-full wp-image-25093\" alt=\"\" srcset=\"https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2024\/11\/qccert.webp 873w, https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2024\/11\/qccert-300x300.webp 300w, https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2024\/11\/qccert-100x100.webp 100w, https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2024\/11\/qccert-600x600.webp 600w, https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2024\/11\/qccert-150x150.webp 150w, https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2024\/11\/qccert-768x768.webp 768w, https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2024\/11\/qccert-50x50.webp 50w\" sizes=\"(max-width: 873px) 100vw, 873px\" \/><\/figure><div class=\"elementor-image-box-content\"><h5 class=\"elementor-image-box-title\">QC Cert<\/h5><p class=\"elementor-image-box-description\">Organismo brasile\u00f1o especializado en la certificaci\u00f3n de productos y sistemas de gesti\u00f3n, acreditado por Inmetro.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ed9001 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"7ed9001\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"301\" height=\"301\" src=\"https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2026\/03\/29-anos.webp\" class=\"attachment-full size-full wp-image-35620\" alt=\"\" srcset=\"https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2026\/03\/29-anos.webp 301w, https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2026\/03\/29-anos-100x100.webp 100w, https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2026\/03\/29-anos-50x50.webp 50w\" sizes=\"(max-width: 301px) 100vw, 301px\" \/><\/figure><div class=\"elementor-image-box-content\"><h5 class=\"elementor-image-box-title\">Metahospitalar<\/h5><p class=\"elementor-image-box-description\">29 a\u00f1os de experiencia desarrollando mobiliario hospitalario con ingenier\u00eda de precisi\u00f3n, dise\u00f1o innovador y tecnolog\u00eda de punta para la salud.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8f24da6 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"8f24da6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"301\" height=\"301\" src=\"https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2026\/03\/garantia-de-qualidade.png\" class=\"attachment-full size-full wp-image-35621\" alt=\"\" srcset=\"https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2026\/03\/garantia-de-qualidade.png 301w, https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2026\/03\/garantia-de-qualidade-100x100.png 100w, https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2026\/03\/garantia-de-qualidade-50x50.png 50w\" sizes=\"(max-width: 301px) 100vw, 301px\" \/><\/figure><div class=\"elementor-image-box-content\"><h5 class=\"elementor-image-box-title\">Garant\u00eda de calidad.<\/h5><p class=\"elementor-image-box-description\">Cada producto Metahospitalar se fabrica con precisi\u00f3n, seguridad y conformidad con las normas del sector m\u00e9dico.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b774828 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"b774828\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1062\" height=\"1061\" src=\"https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2026\/03\/selo-de-qualidade-nicovida.png\" class=\"attachment-full size-full wp-image-35622\" alt=\"\" srcset=\"https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2026\/03\/selo-de-qualidade-nicovida.png 1062w, https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2026\/03\/selo-de-qualidade-nicovida-500x500.png 500w, https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2026\/03\/selo-de-qualidade-nicovida-300x300.png 300w, https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2026\/03\/selo-de-qualidade-nicovida-768x767.png 768w, https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2026\/03\/selo-de-qualidade-nicovida-600x599.png 600w, https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2026\/03\/selo-de-qualidade-nicovida-100x100.png 100w, https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2026\/03\/selo-de-qualidade-nicovida-50x50.png 50w\" sizes=\"(max-width: 1062px) 100vw, 1062px\" \/><\/figure><div class=\"elementor-image-box-content\"><h5 class=\"elementor-image-box-title\">Garant\u00eda de calidad Nicovida<\/h5><p class=\"elementor-image-box-description\">Calidad certificada y desempe\u00f1o confiable para el cuidado hospitalario diario.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b379ac1 e-flex e-con-boxed e-con e-parent\" data-id=\"b379ac1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-534e811 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"534e811\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Conozca nuestra Misi\u00f3n <mark style=\"color:#969696\">\u2022 Visi\u00f3n \u2022 Valores<\/mark><\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-122c49a e-flex e-con-boxed e-con e-parent\" data-id=\"122c49a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-9c388b2 e-con-full e-flex e-con e-child\" data-id=\"9c388b2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5994d3d elementor-position-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"5994d3d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInUp&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"240\" height=\"218\" src=\"https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2023\/12\/missao.webp\" class=\"attachment-medium size-medium wp-image-22603\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Misi\u00f3n<\/h3><p class=\"elementor-image-box-description\">Fabricar, comercializar y distribuir equipos para el segmento m\u00e9dico-hospitalario, incorporando tecnolog\u00eda, conectividad y conocimiento al negocio, con el objetivo de superar y sorprender las expectativas del mercado, teniendo como prop\u00f3sito la sostenibilidad ambiental, social y financiera.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7524b99 e-con-full e-flex e-con e-child\" data-id=\"7524b99\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d7efa16 elementor-position-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"d7efa16\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInUp&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"246\" height=\"249\" src=\"https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2023\/12\/visao.webp\" class=\"attachment-medium size-medium wp-image-22605\" alt=\"\" srcset=\"https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2023\/12\/visao.webp 246w, https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2023\/12\/visao-100x100.webp 100w, https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2023\/12\/visao-50x50.webp 50w\" sizes=\"(max-width: 246px) 100vw, 246px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Visi\u00f3n<\/h3><p class=\"elementor-image-box-description\">Consolidar el liderazgo nacional como una marca reconocida en el mercado internacional, alcanzando el estatus de una empresa de clase mundial.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1d22fb4 e-flex e-con-boxed e-con e-parent\" data-id=\"1d22fb4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1b70ccd elementor-position-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"1b70ccd\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInUp&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"182\" height=\"229\" src=\"https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2023\/12\/valores.webp\" class=\"attachment-medium size-medium wp-image-22601\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Valores<\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-97a2eed e-flex e-con-boxed e-con e-parent\" data-id=\"97a2eed\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d1b6775 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"d1b6775\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><strong>\u00c9tica<br><\/strong>Seguir siempre el principio \u00e9tico y profesional con respeto a las diversidades humanas.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-20795b8 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"20795b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><strong>Respeto<br><\/strong>Buscar una buena relaci\u00f3n con todos los profesionales, clientes, proveedores e inversionistas.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-949d897 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"949d897\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><strong>Gesti\u00f3n Humanizada<br><\/strong>Valorar las relaciones humanas e invertir en la gesti\u00f3n de personas.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-16a9f19 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"16a9f19\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><strong>Innovaci\u00f3n | Criatividad<br><\/strong>Invertir en ingenier\u00eda con tecnolog\u00eda, conocimiento cient\u00edfico, investigaci\u00f3n y desarrollo para la mejora y calidad continua.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-53223c8 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"53223c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><strong>Responsabilidad Socioambiental<br><\/strong>Contribuir al desarrollo socioambiental global, teniendo como meta el ejercicio consciente de la ciudadan\u00eda.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bf32319 e-flex e-con-boxed e-con e-parent\" data-id=\"bf32319\" data-element_type=\"container\" data-e-type=\"container\" id=\"conhe\u00e7a\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fa98617 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"fa98617\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"#conhe\u00e7a\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Conozca nuestra estructura <mark style=\"color:#969696\">Industrial sostenible<\/mark><\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6c33ea6 e-flex e-con-boxed e-con e-parent\" data-id=\"6c33ea6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4f563e9 e-con-full e-flex e-con e-child\" data-id=\"4f563e9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-4fa2102 e-con-full e-flex e-con e-child\" data-id=\"4fa2102\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-df3bae7 elementor-view-stacked elementor-shape-circle elementor-widget elementor-widget-icon\" data-id=\"df3bae7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-solar-panel\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M431.98 448.01l-47.97.05V416h-128v32.21l-47.98.05c-8.82.01-15.97 7.16-15.98 15.99l-.05 31.73c-.01 8.85 7.17 16.03 16.02 16.02l223.96-.26c8.82-.01 15.97-7.16 15.98-15.98l.04-31.73c.01-8.85-7.17-16.03-16.02-16.02zM585.2 26.74C582.58 11.31 568.99 0 553.06 0H86.93C71 0 57.41 11.31 54.79 26.74-3.32 369.16.04 348.08.03 352c-.03 17.32 14.29 32 32.6 32h574.74c18.23 0 32.51-14.56 32.59-31.79.02-4.08 3.35 16.95-54.76-325.47zM259.83 64h120.33l9.77 96H250.06l9.77-96zm-75.17 256H71.09L90.1 208h105.97l-11.41 112zm16.29-160H98.24l16.29-96h96.19l-9.77 96zm32.82 160l11.4-112h149.65l11.4 112H233.77zm195.5-256h96.19l16.29 96H439.04l-9.77-96zm26.06 256l-11.4-112H549.9l19.01 112H455.33z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-98b5a3d elementor-widget elementor-widget-counter\" data-id=\"98b5a3d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Producci\u00f3n alimentada por energ\u00eda sostenible<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"100\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\">%<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a544d84 e-con-full e-flex e-con e-child\" data-id=\"a544d84\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-37dc37f elementor-view-stacked elementor-shape-circle elementor-widget elementor-widget-icon\" data-id=\"37dc37f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-water\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M562.1 383.9c-21.5-2.4-42.1-10.5-57.9-22.9-14.1-11.1-34.2-11.3-48.2 0-37.9 30.4-107.2 30.4-145.7-1.5-13.5-11.2-33-9.1-46.7 1.8-38 30.1-106.9 30-145.2-1.7-13.5-11.2-33.3-8.9-47.1 2-15.5 12.2-36 20.1-57.7 22.4-7.9.8-13.6 7.8-13.6 15.7v32.2c0 9.1 7.6 16.8 16.7 16 28.8-2.5 56.1-11.4 79.4-25.9 56.5 34.6 137 34.1 192 0 56.5 34.6 137 34.1 192 0 23.3 14.2 50.9 23.3 79.1 25.8 9.1.8 16.7-6.9 16.7-16v-31.6c.1-8-5.7-15.4-13.8-16.3zm0-144c-21.5-2.4-42.1-10.5-57.9-22.9-14.1-11.1-34.2-11.3-48.2 0-37.9 30.4-107.2 30.4-145.7-1.5-13.5-11.2-33-9.1-46.7 1.8-38 30.1-106.9 30-145.2-1.7-13.5-11.2-33.3-8.9-47.1 2-15.5 12.2-36 20.1-57.7 22.4-7.9.8-13.6 7.8-13.6 15.7v32.2c0 9.1 7.6 16.8 16.7 16 28.8-2.5 56.1-11.4 79.4-25.9 56.5 34.6 137 34.1 192 0 56.5 34.6 137 34.1 192 0 23.3 14.2 50.9 23.3 79.1 25.8 9.1.8 16.7-6.9 16.7-16v-31.6c.1-8-5.7-15.4-13.8-16.3zm0-144C540.6 93.4 520 85.4 504.2 73 490.1 61.9 470 61.7 456 73c-37.9 30.4-107.2 30.4-145.7-1.5-13.5-11.2-33-9.1-46.7 1.8-38 30.1-106.9 30-145.2-1.7-13.5-11.2-33.3-8.9-47.1 2-15.5 12.2-36 20.1-57.7 22.4-7.9.8-13.6 7.8-13.6 15.7v32.2c0 9.1 7.6 16.8 16.7 16 28.8-2.5 56.1-11.4 79.4-25.9 56.5 34.6 137 34.1 192 0 56.5 34.6 137 34.1 192 0 23.3 14.2 50.9 23.3 79.1 25.8 9.1.8 16.7-6.9 16.7-16v-31.6c.1-8-5.7-15.4-13.8-16.3z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb52f2b elementor-widget elementor-widget-counter\" data-id=\"bb52f2b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">El agua utilizada en el ba\u00f1o de las piezas es tratada<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"100\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\">%<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9423784 e-con-full e-flex e-con e-child\" data-id=\"9423784\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-447f403 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"447f403\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1429\" src=\"https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2026\/03\/Telhado-metahospitalar-scaled.webp\" class=\"attachment-full size-full wp-image-35615\" alt=\"\" srcset=\"https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2026\/03\/Telhado-metahospitalar-scaled.webp 2560w, https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2026\/03\/Telhado-metahospitalar-500x279.webp 500w, https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2026\/03\/Telhado-metahospitalar-1200x670.webp 1200w, https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2026\/03\/Telhado-metahospitalar-300x167.webp 300w, https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2026\/03\/Telhado-metahospitalar-768x429.webp 768w, https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2026\/03\/Telhado-metahospitalar-1536x857.webp 1536w, https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2026\/03\/Telhado-metahospitalar-2048x1143.webp 2048w, https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2026\/03\/Telhado-metahospitalar-600x335.webp 600w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-404937f elementor-widget elementor-widget-image\" data-id=\"404937f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1429\" src=\"https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2026\/03\/ETE-METAHOSPITALAR-scaled.webp\" class=\"attachment-full size-full wp-image-35616\" alt=\"\" srcset=\"https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2026\/03\/ETE-METAHOSPITALAR-scaled.webp 2560w, https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2026\/03\/ETE-METAHOSPITALAR-500x279.webp 500w, https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2026\/03\/ETE-METAHOSPITALAR-1200x670.webp 1200w, https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2026\/03\/ETE-METAHOSPITALAR-300x167.webp 300w, https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2026\/03\/ETE-METAHOSPITALAR-768x429.webp 768w, https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2026\/03\/ETE-METAHOSPITALAR-1536x857.webp 1536w, https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2026\/03\/ETE-METAHOSPITALAR-2048x1143.webp 2048w, https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2026\/03\/ETE-METAHOSPITALAR-600x335.webp 600w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-36a973a e-flex e-con-boxed e-con e-parent\" data-id=\"36a973a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-668c135 e-con-full e-flex e-con e-child\" data-id=\"668c135\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0bfad3e e-con-full e-flex e-con e-child\" data-id=\"0bfad3e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-109509f e-con-full e-flex e-con e-child\" data-id=\"109509f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ad8d2cc elementor-widget elementor-widget-heading\" data-id=\"ad8d2cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Excelencia reconocida en la Feria Hospitalar.<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f32506 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"6f32506\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Layer_1\" viewBox=\"0 0 40 40\"><path d=\"M20,0C9,0,0,9,0,20s9,20,20,20,20-9,20-20S31,0,20,0ZM28.6,20h0c0,.1,0,.2,0,.3,0,0,0,0,0,0h0c0,0,0,.1-.1.2h0s-6.9,7-6.9,7c-.2.3-.7.3-.9,0,0,0,0,0,0,0-.3-.3-.3-.7,0-.9,0,0,0,0,0,0l5.8-5.9h-14.5c-.4,0-.6-.3-.6-.7,0-.4.3-.6.6-.6h14.5l-5.8-5.9c-.2-.3-.2-.7,0-.9.3-.2.7-.2.9,0l6.9,7h0c0,0,0,.1.1.2h0s0,0,0,0h0c0,0,0,.2,0,.2h0s0,0,0,0Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-631a029 elementor-widget elementor-widget-text-editor\" data-id=\"631a029\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"316\" data-end=\"607\">En la mayor feria de salud de Am\u00e9rica Latina, Metahospitalar presenta su ingenier\u00eda, innovaci\u00f3n y capacidad industrial en un stand premiado durante tres ediciones consecutivas.<br>Un espacio creado para acercar a los profesionales de la salud a las tecnolog\u00edas que transforman el cuidado hospitalario. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Conozca de cerca Metahospitalar. Lo invitamos a conocer nuestra estructura industrial, nuestros productos y las soluciones que desarrollamos para hospitales e instituciones de salud. Conocer Nuestra Pol\u00edtica de Calidad Pol\u00edtica de calidad Atender, superar y sorprender las expectativas del mercado mediante una excelente atenci\u00f3n, proporcionando mobiliario hospitalario de desempe\u00f1o superior. Valorar la capacitaci\u00f3n y el [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"googlesitekit_rrm_CAow0fHbCw:productID":"","content-type":"","footnotes":""},"class_list":["post-35623","page","type-page","status-publish","hentry"],"blocksy_meta":{"has_hero_section":"disabled","vertical_spacing_source":"custom","content_area_spacing":"none","styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":6}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sobre nosotros - Metahospitalar<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/metahospitalar.com.br\/es\/sobre-nosotros\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sobre nosotros - Metahospitalar\" \/>\n<meta property=\"og:description\" content=\"Conozca de cerca Metahospitalar. Lo invitamos a conocer nuestra estructura industrial, nuestros productos y las soluciones que desarrollamos para hospitales e instituciones de salud. Conocer Nuestra Pol\u00edtica de Calidad Pol\u00edtica de calidad Atender, superar y sorprender las expectativas del mercado mediante una excelente atenci\u00f3n, proporcionando mobiliario hospitalario de desempe\u00f1o superior. Valorar la capacitaci\u00f3n y el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/metahospitalar.com.br\/es\/sobre-nosotros\/\" \/>\n<meta property=\"og:site_name\" content=\"Metahospitalar\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/metahospitalar\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T14:41:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2024\/02\/politica-de-qualidade.png\" \/>\n\t<meta property=\"og:image:width\" content=\"168\" \/>\n\t<meta property=\"og:image:height\" content=\"196\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Metahospitalar\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/metahospitalar.com.br\\\/es\\\/sobre-nosotros\\\/\",\"url\":\"https:\\\/\\\/metahospitalar.com.br\\\/es\\\/sobre-nosotros\\\/\",\"name\":\"Sobre nosotros - Metahospitalar\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/metahospitalar.com.br\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/metahospitalar.com.br\\\/es\\\/sobre-nosotros\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/metahospitalar.com.br\\\/es\\\/sobre-nosotros\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/metahospitalar.com.br\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/politica-de-qualidade.png\",\"datePublished\":\"2025-09-10T17:35:11+00:00\",\"dateModified\":\"2026-05-12T14:41:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/metahospitalar.com.br\\\/es\\\/sobre-nosotros\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/metahospitalar.com.br\\\/es\\\/sobre-nosotros\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/metahospitalar.com.br\\\/es\\\/sobre-nosotros\\\/#primaryimage\",\"url\":\"https:\\\/\\\/metahospitalar.com.br\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/politica-de-qualidade.png\",\"contentUrl\":\"https:\\\/\\\/metahospitalar.com.br\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/politica-de-qualidade.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/metahospitalar.com.br\\\/es\\\/sobre-nosotros\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/metahospitalar.com.br\\\/es\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sobre nosotros\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/metahospitalar.com.br\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/metahospitalar.com.br\\\/es\\\/\",\"name\":\"Metahospitalar\",\"description\":\"M\u00f3veis hospitalares\",\"publisher\":{\"@id\":\"https:\\\/\\\/metahospitalar.com.br\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/metahospitalar.com.br\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/metahospitalar.com.br\\\/es\\\/#organization\",\"name\":\"metahospitalar\",\"alternateName\":\"Meta m\u00f3veis\",\"url\":\"https:\\\/\\\/metahospitalar.com.br\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/metahospitalar.com.br\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/metahospitalar.com.br\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/META-HOSPITALAR-curva-icone-copiar.webp\",\"contentUrl\":\"https:\\\/\\\/metahospitalar.com.br\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/META-HOSPITALAR-curva-icone-copiar.webp\",\"width\":512,\"height\":512,\"caption\":\"metahospitalar\"},\"image\":{\"@id\":\"https:\\\/\\\/metahospitalar.com.br\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/metahospitalar\",\"https:\\\/\\\/x.com\\\/Metahospitalar\",\"https:\\\/\\\/www.instagram.com\\\/metahospitalar\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/metahospitalar\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sobre nosotros - Metahospitalar","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/metahospitalar.com.br\/es\/sobre-nosotros\/","og_locale":"es_ES","og_type":"article","og_title":"Sobre nosotros - Metahospitalar","og_description":"Conozca de cerca Metahospitalar. Lo invitamos a conocer nuestra estructura industrial, nuestros productos y las soluciones que desarrollamos para hospitales e instituciones de salud. Conocer Nuestra Pol\u00edtica de Calidad Pol\u00edtica de calidad Atender, superar y sorprender las expectativas del mercado mediante una excelente atenci\u00f3n, proporcionando mobiliario hospitalario de desempe\u00f1o superior. Valorar la capacitaci\u00f3n y el [&hellip;]","og_url":"https:\/\/metahospitalar.com.br\/es\/sobre-nosotros\/","og_site_name":"Metahospitalar","article_publisher":"https:\/\/www.facebook.com\/metahospitalar","article_modified_time":"2026-05-12T14:41:50+00:00","og_image":[{"width":168,"height":196,"url":"https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2024\/02\/politica-de-qualidade.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@Metahospitalar","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/metahospitalar.com.br\/es\/sobre-nosotros\/","url":"https:\/\/metahospitalar.com.br\/es\/sobre-nosotros\/","name":"Sobre nosotros - Metahospitalar","isPartOf":{"@id":"https:\/\/metahospitalar.com.br\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/metahospitalar.com.br\/es\/sobre-nosotros\/#primaryimage"},"image":{"@id":"https:\/\/metahospitalar.com.br\/es\/sobre-nosotros\/#primaryimage"},"thumbnailUrl":"https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2024\/02\/politica-de-qualidade.png","datePublished":"2025-09-10T17:35:11+00:00","dateModified":"2026-05-12T14:41:50+00:00","breadcrumb":{"@id":"https:\/\/metahospitalar.com.br\/es\/sobre-nosotros\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/metahospitalar.com.br\/es\/sobre-nosotros\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/metahospitalar.com.br\/es\/sobre-nosotros\/#primaryimage","url":"https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2024\/02\/politica-de-qualidade.png","contentUrl":"https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2024\/02\/politica-de-qualidade.png"},{"@type":"BreadcrumbList","@id":"https:\/\/metahospitalar.com.br\/es\/sobre-nosotros\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/metahospitalar.com.br\/es\/home\/"},{"@type":"ListItem","position":2,"name":"Sobre nosotros"}]},{"@type":"WebSite","@id":"https:\/\/metahospitalar.com.br\/es\/#website","url":"https:\/\/metahospitalar.com.br\/es\/","name":"Metahospitalar","description":"M\u00f3veis hospitalares","publisher":{"@id":"https:\/\/metahospitalar.com.br\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/metahospitalar.com.br\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/metahospitalar.com.br\/es\/#organization","name":"metahospitalar","alternateName":"Meta m\u00f3veis","url":"https:\/\/metahospitalar.com.br\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/metahospitalar.com.br\/es\/#\/schema\/logo\/image\/","url":"https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2022\/06\/META-HOSPITALAR-curva-icone-copiar.webp","contentUrl":"https:\/\/metahospitalar.com.br\/wp-content\/uploads\/2022\/06\/META-HOSPITALAR-curva-icone-copiar.webp","width":512,"height":512,"caption":"metahospitalar"},"image":{"@id":"https:\/\/metahospitalar.com.br\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/metahospitalar","https:\/\/x.com\/Metahospitalar","https:\/\/www.instagram.com\/metahospitalar\/","https:\/\/www.linkedin.com\/company\/metahospitalar\/"]}]}},"_links":{"self":[{"href":"https:\/\/metahospitalar.com.br\/es\/wp-json\/wp\/v2\/pages\/35623","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/metahospitalar.com.br\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/metahospitalar.com.br\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/metahospitalar.com.br\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/metahospitalar.com.br\/es\/wp-json\/wp\/v2\/comments?post=35623"}],"version-history":[{"count":1,"href":"https:\/\/metahospitalar.com.br\/es\/wp-json\/wp\/v2\/pages\/35623\/revisions"}],"predecessor-version":[{"id":35632,"href":"https:\/\/metahospitalar.com.br\/es\/wp-json\/wp\/v2\/pages\/35623\/revisions\/35632"}],"wp:attachment":[{"href":"https:\/\/metahospitalar.com.br\/es\/wp-json\/wp\/v2\/media?parent=35623"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}